{"id":48216,"date":"2025-07-24T08:06:42","date_gmt":"2025-07-24T08:06:42","guid":{"rendered":"https:\/\/tubefurnacecn.com\/?p=48216"},"modified":"2025-08-19T08:02:41","modified_gmt":"2025-08-19T08:02:41","slug":"vacuum-brazing-furnace-for-cutting-tools","status":"publish","type":"post","link":"http:\/\/www.tubefurnacecn.com\/es\/vacuum-brazing-furnace-for-cutting-tools\/","title":{"rendered":"Horno de soldadura al vac\u00edo para herramientas de corte"},"content":{"rendered":"<p>El horno de soldadura al vac\u00edo de la serie 200BF se utiliza ampliamente en la soldadura fuerte de varios tipos de materiales superduros de tama\u00f1o peque\u00f1o, principalmente para herramientas de carburo cementado (herramientas PCD, herramientas PCBN, herramientas CVD, herramientas CBN, herramientas de grabado, etc.), brocas de perforaci\u00f3n, soldadura fuerte de acero inoxidable, soldadura fuerte de cristal \u00fanico, soldadura fuerte de metal de porcelana, componentes met\u00e1licos heterotr\u00f3picos, l\u00e1minas complejas: componentes s\u00e1ndwich, estructura de panal, etc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"qoaob\">Horno de soldadura al vac\u00edo para herramientas de corte Caracter\u00edsticas<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El control total del PLC tambi\u00e9n puede cambiar el control manual, pantalla t\u00e1ctil HD de 10 pulgadas, 50 programas, almacenamiento de 30 programas, operaci\u00f3n simple y producci\u00f3n continua.<\/li>\n\n\n\n<li>Se pueden derivar la curva de temperatura y la curva de vac\u00edo.<\/li>\n\n\n\n<li>La superficie de la pieza de soldadura es limpia y agradable y no presenta oxidaci\u00f3n. Doble plataforma de acero inoxidable, para que los materiales de soldadura fuerte se coloquen en orden.<\/li>\n\n\n\n<li>Usando el anillo y la calefacci\u00f3n inferior, alta fuerza que suelda, 2-3 veces la soldadura fuerte de alta frecuencia ordinaria.<\/li>\n\n\n\n<li>Con una alta capacidad de producci\u00f3n, una sola cantidad de soldadura puede alcanzar m\u00e1s de 600 piezas (tome CNGA1204 como ejemplo).<\/li>\n\n\n\n<li>Proporcionar apoyo t\u00e9cnico y de procesos para garantizar la fabricaci\u00f3n de productos de alta calidad.<\/li>\n\n\n\n<li>El sistema de vac\u00edo consta de una bomba directa y una bomba de difusi\u00f3n, el vac\u00edo final puede alcanzar 7x 10-3Pa (carga vac\u00eda, estado fr\u00edo).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"qk31k\">Proceso de soldadura fuerte<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Limpieza ultras\u00f3nica \u2192desbaste de pasta de soldadura\u2192secado al vac\u00edo\u2192soldadura al vac\u00edo.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"bb4q2\">Piezas opcionales<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00e1quina de refrigeraci\u00f3n por agua<\/li>\n\n\n\n<li>Horno de vac\u00edo<\/li>\n\n\n\n<li>M\u00e1quina de limpieza por ultrasonidos<\/li>\n\n\n\n<li>Pasta fundente<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"61llo\">Par\u00e1metros t\u00e9cnicos del horno de soldadura al vac\u00edo<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><th>Modelo<\/th><th>Temp. Temp. (\u00b0C\uff09<\/th><th>Tama\u00f1o de la c\u00e1mara (Dia*H) mm<\/th><th>Tama\u00f1o (mm)<\/th><th>Potencia (KW)<\/th><th>Termopar<\/th><\/tr><tr><td>200BF<\/td><td>1200<\/td><td>Dia200*400<\/td><td>1235*1150*750<\/td><td>8<\/td><td>Tipo K<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>* Se pueden personalizar otros tama\u00f1os.<\/p>","protected":false},"excerpt":{"rendered":"<p>200BF Series Vacuum Brazing furnace is widely used in the brazing of various kinds of small-size super-hard materials, mainly used for cemented carbide tools (PCD tools, PCBNtools, CVD tools, CBN tools, engraving tools, etc.), drilling bit, stainless steel brazing, single crystal brazing, porcelain metal brazing, heterotropic metal components, complex sheet: sandwich components, honeycomb structure, etc. &#8230; <a title=\"Horno de soldadura al vac\u00edo para herramientas de corte\" class=\"read-more\" href=\"http:\/\/www.tubefurnacecn.com\/es\/vacuum-brazing-furnace-for-cutting-tools\/\" aria-label=\"Leer m\u00e1s sobre Vacuum Brazing Furnace for Cutting Tools\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":1,"featured_media":48317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-48216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vacuum-brazing-furnace"],"_links":{"self":[{"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/posts\/48216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/comments?post=48216"}],"version-history":[{"count":1,"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/posts\/48216\/revisions"}],"predecessor-version":[{"id":48217,"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/posts\/48216\/revisions\/48217"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/media\/48317"}],"wp:attachment":[{"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/media?parent=48216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/categories?post=48216"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/es\/wp-json\/wp\/v2\/tags?post=48216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}