{"id":3,"date":"2025-06-17T07:17:40","date_gmt":"2025-06-17T07:17:40","guid":{"rendered":"http:\/\/tubefurnacecn.com\/?page_id=3"},"modified":"2025-08-07T08:07:26","modified_gmt":"2025-08-07T08:07:26","slug":"privacy-policy","status":"publish","type":"page","link":"http:\/\/www.tubefurnacecn.com\/it\/privacy-policy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Zhengzhou Tuke Furnace Co., Ltd. - Informativa sulla privacy<\/strong><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Introduzione<\/strong><\/h3>\n\n\n\n<p>Zhengzhou Tuke Furnace Co., Ltd. (\"Tuke Furnace\", \"noi\", \"nostro\") gestisce&nbsp;<a href=\"http:\/\/www.tubefurnacecn.com\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.tubefurnacecn.com\/<\/a>&nbsp;come piattaforma informativa per le soluzioni di trattamento termico industriale. Questa politica spiega come raccogliamo, utilizziamo e proteggiamo i dati dei visitatori che interagiscono con la nostra esposizione dei prodotti, gli strumenti di comunicazione online e la corrispondenza via e-mail. Siamo conformi al GDPR, al CCPA e ad altre leggi sulla privacy.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Informazioni raccolte<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>2.1 Informazioni personali (fornite volontariamente)<\/strong><\/h4>\n\n\n\n<p>Raccogliamo dati quando:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Invia un&nbsp;<strong>inchiesta online<\/strong>&nbsp;o&nbsp;<strong>messaggio<\/strong>&nbsp;tramite i nostri moduli di contatto<\/li>\n\n\n\n<li>Inviare la corrispondenza via e-mail ai nostri team di vendita\/tecnici<\/li>\n\n\n\n<li>Richiedere la documentazione sul prodotto (ad esempio, le specifiche del forno a vuoto).<\/li>\n<\/ul>\n\n\n\n<p><em>Categorie raccolte:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dettagli di contatto<\/strong>: Nome e cognome, indirizzo e-mail, numero di telefono, nome dell'azienda, titolo di lavoro.<\/li>\n\n\n\n<li><strong>Contenuto della comunicazione<\/strong>: Richieste tecniche, specifiche delle apparecchiature, requisiti del progetto<\/li>\n\n\n\n<li><strong>Contesto industriale<\/strong>: Settore industriale (ad esempio, semiconduttori, aerospaziale), scala di produzione, esigenze di lavorazione dei materiali.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>2.2 Informazioni tecniche (raccolte automaticamente)<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Analisi del sito web<\/strong>: Indirizzo IP, tipo di dispositivo, versione del browser, pagine visitate (tramite Google Analytics)<\/li>\n\n\n\n<li><strong>Modelli di utilizzo<\/strong>: Tempo trascorso sulle pagine dei prodotti (ad esempio, serie di forni per tubi), link di download cliccati<\/li>\n<\/ul>\n\n\n\n<p><em>Non vengono utilizzati cookie per la pubblicit\u00e0 o il tracciamento degli utenti.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Come utilizziamo le vostre informazioni<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Comunicazione aziendale<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Rispondere alle richieste di informazioni su forni a muffola, sistemi CVD, ecc.<\/li>\n\n\n\n<li>Fornire assistenza tecnica per applicazioni di brasatura o sinterizzazione sotto vuoto<\/li>\n\n\n\n<li>Condividere casi di studio specifici del settore (ad esempio, la lavorazione dei materiali delle batterie).<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Miglioramento del prodotto<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Analizzare le richieste pi\u00f9 comuni per ottimizzare la navigazione del sito web<\/li>\n\n\n\n<li>Identificare le tendenze dei requisiti dei forni industriali<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Conformit\u00e0 legale<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Mantenere i registri per la certificazione ISO 9001<\/li>\n\n\n\n<li>Rispettare le normative sul controllo delle esportazioni per le apparecchiature a duplice uso.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Condivisione e divulgazione dei dati<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fornitori di servizi di terze parti<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Hosting e-mail (Microsoft 365) con protocolli di crittografia<\/li>\n\n\n\n<li>Analisi del sito web (Google Analytics) configurata con l'anonimizzazione dell'IP<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Requisiti legali<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Divulgare i dati alle autorit\u00e0 solo se richiesto dalla legge (ad esempio, la documentazione doganale per le spedizioni internazionali).<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><em>Non vendiamo mai i dati a inserzionisti o a terze parti.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Sicurezza dei dati<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tutte le forme di comunicazione utilizzano&nbsp;<strong>Crittografia SSL<\/strong><\/li>\n\n\n\n<li>Corrispondenza e-mail archiviata in sistemi cloud sicuri<\/li>\n\n\n\n<li>Documenti fisici conservati per max. 3 anni (riferimento al ciclo di vita delle apparecchiature industriali)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6. I vostri diritti<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Accesso\/Rettificazione<\/strong>: Email\u00a0<a href=\"mailto:info@tubefurnacecn.com\" data-type=\"mailto\" data-id=\"mailto:info@tubefurnacecn.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@tubefurnacecn.com<\/a>\u00a0per rivedere o aggiornare i propri dati<\/li>\n\n\n\n<li><strong>Cancellazione<\/strong>: Richiesta di cancellazione dei messaggi online dopo il completamento del progetto<\/li>\n\n\n\n<li><strong>Opt-out<\/strong>: Annullamento dell'iscrizione alle e-mail di marketing tramite link nel footer<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>7. Contatti<\/strong><\/h3>\n\n\n\n<p>Responsabile della protezione dei dati<br>Zhengzhou Tuke Furnace Co., Ltd.<br>Indirizzo: Science Avenue, High tech Zone, Zhengzhou City, provincia di Henan, Cina<br>E-mail:\u00a0<a href=\"mailto:info@tubefurnacecn.com\" data-type=\"mailto\" data-id=\"mailto:info@tubefurnacecn.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@tubefurnacecn.com<\/a><br>Telefono: [Inserire numero di contatto]<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><\/li>\n<\/ol>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Zhengzhou Tuke Furnace Co., Ltd. &#8211; Privacy Policy 1. Introduction Zhengzhou Tuke Furnace Co., Ltd. (&#8220;Tuke Furnace,&#8221; &#8220;we,&#8221; &#8220;our&#8221;) operates&nbsp;http:\/\/www.tubefurnacecn.com\/&nbsp;as an informational platform for industrial heat treatment solutions. This policy explains how we collect, use, and protect data from visitors interacting with our product display, online communication tools, and email correspondence. We comply with GDPR, &#8230; <a title=\"Informativa sulla privacy\" class=\"read-more\" href=\"http:\/\/www.tubefurnacecn.com\/it\/privacy-policy\/\" aria-label=\"Per saperne di pi\u00f9 su Privacy Policy\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish"],"_links":{"self":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":5,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":48295,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/pages\/3\/revisions\/48295"}],"wp:attachment":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}