{"id":48197,"date":"2025-07-24T06:45:25","date_gmt":"2025-07-24T06:45:25","guid":{"rendered":"https:\/\/tubefurnacecn.com\/?p=48197"},"modified":"2025-08-19T07:21:58","modified_gmt":"2025-08-19T07:21:58","slug":"vacuum-tungsten-furnace","status":"publish","type":"post","link":"http:\/\/www.tubefurnacecn.com\/it\/vacuum-tungsten-furnace\/","title":{"rendered":"Forno a vuoto per tungsteno"},"content":{"rendered":"<p>Questo forno a vuoto a filo di tungsteno utilizza un riscaldamento a rete di tungsteno, una temperatura ultraelevata e un'assenza di inquinamento pulito, adatto per la sinterizzazione di ceramica di elevata purezza, ceramica trasparente, vetro zaffiro, zirconia e altri tipi di sinterizzazione sotto vuoto spinto, degassificazione e trattamento di invecchiamento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"qt3nu\">Caratteristiche del forno per tungsteno a vuoto<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rete di tungsteno appositamente progettata, foglio di tungsteno come elemento riscaldante, temperatura massima pu\u00f2 essere 2200\u2103<\/li>\n\n\n\n<li>Il sistema di vuoto adotta una pompa per vuoto a collegamento diretto e una pompa turbo, il cui vuoto finale pu\u00f2 essere di 7\u00d710-4Pa.<\/li>\n\n\n\n<li>HMl adotta un touch screen HD, un sistema operativo integrato sviluppato dalla nostra azienda.<\/li>\n\n\n\n<li>Sistema di controllo automatico PLC.<\/li>\n\n\n\n<li>Pu\u00f2 entrare in N2, Ar, H2, N2 e gas misto H2 ecc.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"garkq\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"garkq\">Parti opzionali del forno a vuoto in grafite<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Macchina per il raffreddamento ad acqua<\/li>\n\n\n\n<li>Crogiolo di grafite<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Parametri tecnici<\/h2>\n\n\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><th>Modello<\/th><th>Temperatura di lavoro<br>(\u2103)<\/th><th>Dimensioni della camera (mm)<br>(Dia*H) mm<\/th><th>Potenza<br>(kW)<\/th><th>Tensione<br>(V)<\/th><th>Massimo. Vuoto<\/th><\/tr><tr><td>WSL-1020<\/td><td>2200<\/td><td>Dia100*200<\/td><td>60<\/td><td>380V<\/td><td>7\u00d710-4 Pa<\/td><\/tr><tr><td>WSL-2040<\/td><td>2200<\/td><td>Dia200*400<\/td><td>160<\/td><td>380V<\/td><td>7\u00d710-4 Pa<\/td><\/tr><tr><td>WSL-3050<\/td><td>2200<\/td><td>Dia300*500<\/td><td>250<\/td><td>380V<\/td><td>7\u00d710-4 Pa<\/td><\/tr><tr><td>WSL-4060<\/td><td>2200<\/td><td>Dia400*600<\/td><td>340<\/td><td>380V<\/td><td>7\u00d710-4 Pa<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>* Altre dimensioni possono essere personalizzate.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>This vacuum tungsten wire furnace uses tungsten mesh heating, ultra-high temperature, and clean pollution-free, suitable for high purity ceramic sintering transparent ceramics, sapphire glass, zirconia, and other sintering under high vacuum, degassing, and aging treatment. lt is also suitable for pilot-scale production and use in universities and scientific research institutes. Vacuum Tungsten Furnace Features Graphite &#8230; <a title=\"Forno a vuoto per tungsteno\" class=\"read-more\" href=\"http:\/\/www.tubefurnacecn.com\/it\/vacuum-tungsten-furnace\/\" aria-label=\"Per saperne di pi\u00f9 su Vacuum Tungsten Furnace\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":48310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-48197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vacuum-sintering-furnace"],"_links":{"self":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/posts\/48197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/comments?post=48197"}],"version-history":[{"count":2,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/posts\/48197\/revisions"}],"predecessor-version":[{"id":48213,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/posts\/48197\/revisions\/48213"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/media\/48310"}],"wp:attachment":[{"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/media?parent=48197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/categories?post=48197"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.tubefurnacecn.com\/it\/wp-json\/wp\/v2\/tags?post=48197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}